{"id":10871,"date":"2020-05-18T22:42:18","date_gmt":"2020-05-18T20:42:18","guid":{"rendered":"https:\/\/wp.jochen.hayek.name\/blog-de\/?p=10871"},"modified":"2020-09-30T11:19:44","modified_gmt":"2020-09-30T09:19:44","slug":"covid-19-preise-wiederaufladbare-batterien","status":"publish","type":"post","link":"https:\/\/wp.jochen.hayek.name\/blog-de\/2020\/05\/18\/covid-19-preise-wiederaufladbare-batterien\/","title":{"rendered":"Covid-19-Preise bei Saturn und bei Amazon: wiederaufladbare Batterien von Panasonic, AAA und AA \u2013 derzeitige Preise"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.amazon.de\/dp\/B00JVV8PS8\">https:\/\/www.amazon.de\/dp\/B00JVV8PS8<\/a> : 4 AAA Batterien bei Amazon f\u00fcr 10 Euro, bei Saturn f\u00fcr 17 Euro<\/li><li><a href=\"https:\/\/www.amazon.de\/dp\/B00IWS52MI\">https:\/\/www.amazon.de\/dp\/B00IWS52MI<\/a> : 4 AA-Batterien bei Amazon f\u00fcr 13 Euro, bei Saturn derzeit f\u00fcr 17 Euro<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Mir stockte der Atem, als ich diese Preise bei Saturn im Europa-Center heute sah. Ich brauchte die AA-Akkus unbedingt, also biss ich in den sauren Apfel. Ich halte das f\u00fcr Wucher. Aber wahrscheinlich geht es Saturn in dieser Phase des Lockdown so schlecht, dass es keine andere Wahl hat, als solche Preise aufzurufen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/www.amazon.de\/dp\/B00JVV8PS8 : 4 AAA Batterien bei Amazon f\u00fcr 10 Euro, bei Saturn f\u00fcr 17 Euro https:\/\/www.amazon.de\/dp\/B00IWS52MI : 4 AA-Batterien bei Amazon f\u00fcr 13 Euro, bei Saturn derzeit f\u00fcr 17 Euro Mir stockte der Atem, als ich diese Preise bei Saturn im Europa-Center heute sah. Ich brauchte die AA-Akkus unbedingt, also biss ich in den sauren [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_share_on_mastodon":"0"},"categories":[1452,168,195],"tags":[],"class_list":["post-10871","post","type-post","status-publish","format-standard","hentry","category-covid-19","category-gesundheit","category-haushalt"],"share_on_mastodon":{"url":"","error":""},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paO0l8-2Pl","jetpack_likes_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/10871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/comments?post=10871"}],"version-history":[{"count":1,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/10871\/revisions"}],"predecessor-version":[{"id":10872,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/10871\/revisions\/10872"}],"wp:attachment":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/media?parent=10871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/categories?post=10871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/tags?post=10871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}