{"id":1275,"date":"2011-08-23T22:16:00","date_gmt":"2011-08-23T22:16:00","guid":{"rendered":"http:\/\/www.b.shuttle.de\/hayek\/Hayek\/Jochen\/wp\/blog-de\/2011\/08\/23\/peilomat-du-haeltst-den-regen-nicht-auf\/"},"modified":"2011-08-23T22:16:00","modified_gmt":"2011-08-23T22:16:00","slug":"peilomat-du-haeltst-den-regen-nicht-auf","status":"publish","type":"post","link":"https:\/\/wp.jochen.hayek.name\/blog-de\/2011\/08\/23\/peilomat-du-haeltst-den-regen-nicht-auf\/","title":{"rendered":"PEILOMAT &#8211; DU H\u00c4LTST DEN REGEN NICHT AUF"},"content":{"rendered":"<p>\t\t\t\t<a href=\"http:\/\/www.youtube.com\/watch?v=Fd1TXHww9-Q&amp;feature=youtube_gdata_player\">PEILOMAT &#8211; DU H\u00c4LTST DEN REGEN NICHT AUF<\/a>: Die neue Single &#8220;Du h\u00e4ltst den Regen nicht auf&#8221; von Peilomat kommt am 25.03.2011! Das Album ICHERZ\u00c4HLER erscheint am 1. April und die gleichnamige Tour begin&#8230;\t\t\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PEILOMAT &#8211; DU H\u00c4LTST DEN REGEN NICHT AUF: Die neue Single &#8220;Du h\u00e4ltst den Regen nicht auf&#8221; von Peilomat kommt am 25.03.2011! Das Album ICHERZ\u00c4HLER erscheint am 1. April und die gleichnamige Tour begin&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_share_on_mastodon":"0"},"categories":[103],"tags":[],"class_list":["post-1275","post","type-post","status-publish","format-standard","hentry","category-die-musik"],"share_on_mastodon":{"url":"","error":""},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paO0l8-kz","jetpack_likes_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/1275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/comments?post=1275"}],"version-history":[{"count":0,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/1275\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/media?parent=1275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/categories?post=1275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/tags?post=1275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}