{"id":13027,"date":"2022-12-07T08:00:00","date_gmt":"2022-12-07T07:00:00","guid":{"rendered":"https:\/\/wp.jochen.hayek.name\/blog-de\/?p=13027"},"modified":"2022-12-07T19:05:07","modified_gmt":"2022-12-07T18:05:07","slug":"raben-kalender-2022-12-07","status":"publish","type":"post","link":"https:\/\/wp.jochen.hayek.name\/blog-de\/2022\/12\/07\/raben-kalender-2022-12-07\/","title":{"rendered":"Kalender-Blatt vom 07. Dezember 2022"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Wieder mal sagenhaft deprimiert, qu\u00e4lende, wirklich schmerzhafte Langeweile, ideen- und antriebslos bis zur L\u00e4hmung. Einer der unz\u00e4hligen Tage, die verstreichen, ohne auch nur die kleinste Spur zu hinterlassen.<\/p>\n<cite>Heinz Strunk, Nach Notat zu Bett<\/cite><\/blockquote>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/de.wikipedia.org\/wiki\/Heinz_Strunk\">https:\/\/de.wikipedia.org\/wiki\/Heinz_Strunk<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/de.wikipedia.org\/wiki\/Spezial:ISBN-Suche\/9783498001247\">https:\/\/de.wikipedia.org\/wiki\/Spezial:ISBN-Suche\/9783498001247<\/a> \u2013 &#8220;Nach Notat zu Bett&#8221;<\/li>\n<\/ul>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Wieder mal sagenhaft deprimiert, qu\u00e4lende, wirklich schmerzhafte Langeweile, ideen- und antriebslos bis zur L\u00e4hmung. Einer der unz\u00e4hligen Tage, die verstreichen, ohne auch nur die kleinste Spur zu hinterlassen. Heinz Strunk, Nach Notat zu Bett<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_share_on_mastodon":"0"},"categories":[418],"tags":[],"class_list":["post-13027","post","type-post","status-publish","format-standard","hentry","category-raben-kalender"],"share_on_mastodon":{"url":"","error":""},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paO0l8-3o7","jetpack_likes_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/13027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/comments?post=13027"}],"version-history":[{"count":2,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/13027\/revisions"}],"predecessor-version":[{"id":13186,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/13027\/revisions\/13186"}],"wp:attachment":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/media?parent=13027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/categories?post=13027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/tags?post=13027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}