{"id":140,"date":"2013-10-19T10:06:00","date_gmt":"2013-10-19T10:06:00","guid":{"rendered":"http:\/\/www.b.shuttle.de\/hayek\/Hayek\/Jochen\/wp\/blog-de\/2013\/10\/19\/probleme-mit-podcasts-auf-meiner-fritzbox-7390-fritzos-05-60-26687-rc\/"},"modified":"2013-10-19T10:06:00","modified_gmt":"2013-10-19T10:06:00","slug":"probleme-mit-podcasts-auf-meiner-fritzbox-7390-fritzos-05-60-26687-rc","status":"publish","type":"post","link":"https:\/\/wp.jochen.hayek.name\/blog-de\/2013\/10\/19\/probleme-mit-podcasts-auf-meiner-fritzbox-7390-fritzos-05-60-26687-rc\/","title":{"rendered":"Probleme mit Podcasts auf meiner FRITZ!Box 7390 (FRITZ!OS 05.60-26687 RC)"},"content":{"rendered":"<p>\t\t\t\t<a href=\"http:\/\/www.dradiowissen.de\/podcast.56.de.html\">http:\/\/www.dradiowissen.de\/podcast.56.de.html<\/a><\/p>\n<p>Auf dem MT-F werden nicht die Artikel aus demjenigen Podcast-Feed angezeigt, den ich erwarte \u2026\t\t\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>http:\/\/www.dradiowissen.de\/podcast.56.de.html Auf dem MT-F werden nicht die Artikel aus demjenigen Podcast-Feed angezeigt, den ich erwarte \u2026<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_share_on_mastodon":"0"},"categories":[352],"tags":[],"class_list":["post-140","post","type-post","status-publish","format-standard","hentry","category-nicht-zugeordnet"],"share_on_mastodon":{"url":"","error":""},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paO0l8-2g","jetpack_likes_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/comments?post=140"}],"version-history":[{"count":0,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/140\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/media?parent=140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/categories?post=140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/tags?post=140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}