{"id":282,"date":"2013-05-13T20:00:00","date_gmt":"2013-05-13T20:00:00","guid":{"rendered":"http:\/\/www.b.shuttle.de\/hayek\/Hayek\/Jochen\/wp\/blog-de\/2013\/05\/13\/reset-der-fritzbox-aka-werkseinstellungen-laden\/"},"modified":"2013-05-13T20:00:00","modified_gmt":"2013-05-13T20:00:00","slug":"reset-der-fritzbox-aka-werkseinstellungen-laden","status":"publish","type":"post","link":"https:\/\/wp.jochen.hayek.name\/blog-de\/2013\/05\/13\/reset-der-fritzbox-aka-werkseinstellungen-laden\/","title":{"rendered":"Reset der FRITZ!Box AKA &#8220;Werkseinstellungen laden&#8221;"},"content":{"rendered":"<p>\t\t\t\tTja, wenn man meint, seine FRITZ!Box gar nicht mehr erreichen zu k\u00f6nnen, denkt man an einen Reset \u00fcber eine passende Taste. So ich gerade auch. Aber so eine von au\u00dfen zug\u00e4ngliche Taste gibt es an der FRITZ!Box nicht. Stattdessen kann man in der Benutzeroberfl\u00e4che an der einen oder anderen Stelle auf einen passenden Link dr\u00fccken oder auf einem angeschlossenen Telefon eine passende Tastenkombination eintippen. Ich hatte meine alte FRITZ!Box 7270 (V2) aber irgendwann einmal so verstellt, dass ich sie als &#8220;fritz.box&#8221; im LAN nicht mehr erreichen konnte. Der Weg \u00fcber die Oberfl\u00e4che schien mir also verbaut, und ein passendes Telefon hatte ich hier &#8220;im Exil&#8221; auch nicht zur Hand. Aber eine Web-Suche f\u00fchrte mich zu einem Artikel, der erl\u00e4uterte, dass jede FRITZ!Box auch immer \u00fcber\u00a0<a href=\"http:\/\/169.254.1.1\/\">http:\/\/169.254.1.1<\/a> erreichbar ist. Von da ab war alles wieder ganz leicht in Ordnung gebracht. Ich brauchte auch den Reset nicht mehr.\t\t\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tja, wenn man meint, seine FRITZ!Box gar nicht mehr erreichen zu k\u00f6nnen, denkt man an einen Reset \u00fcber eine passende Taste. So ich gerade auch. Aber so eine von au\u00dfen zug\u00e4ngliche Taste gibt es an der FRITZ!Box nicht. Stattdessen kann man in der Benutzeroberfl\u00e4che an der einen oder anderen Stelle auf einen passenden Link dr\u00fccken [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_share_on_mastodon":"0"},"categories":[352],"tags":[],"class_list":["post-282","post","type-post","status-publish","format-standard","hentry","category-nicht-zugeordnet"],"share_on_mastodon":{"url":"","error":""},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paO0l8-4y","jetpack_likes_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/comments?post=282"}],"version-history":[{"count":0,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/282\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/media?parent=282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/categories?post=282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/tags?post=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}