{"id":342,"date":"2013-01-07T19:00:00","date_gmt":"2013-01-07T19:00:00","guid":{"rendered":"http:\/\/www.b.shuttle.de\/hayek\/Hayek\/Jochen\/wp\/blog-de\/2013\/01\/07\/der-raben-kalender-von-zweitausendeins-raben-kalender\/"},"modified":"2013-01-07T19:00:00","modified_gmt":"2013-01-07T19:00:00","slug":"der-raben-kalender-von-zweitausendeins-raben-kalender","status":"publish","type":"post","link":"https:\/\/wp.jochen.hayek.name\/blog-de\/2013\/01\/07\/der-raben-kalender-von-zweitausendeins-raben-kalender\/","title":{"rendered":"der Raben-Kalender von Zweitausendeins: Raben-Kalender"},"content":{"rendered":"<p>\t\t\t\t<a href=\"http:\/\/www.zweitausendeins.de\/raben-kalender-2013.html\">Raben-Kalender 2013 f\u00fcr 16.95 \u20ac<\/a><\/p>\n<p>Einige Tage vor Weihnachten rief ich noch im Landen in der Kantstra\u00dfe (Berlin-Charlottenburg) an mit den dringenden und konkreten Wunsch, mir ein 3-er Paket zur\u00fccklegen zu lassen. &#8220;Nein, nein, gar nicht n\u00f6tig, wir haben noch genug.&#8221; Und als ich dann kurz nach dem Jahreswechsel den Weg in den Laden fand, war er doch vergriffen. (&#8220;N\u00f6, in den anderen L\u00e4den gibt&#8217;s garantiert auch keine mehr.&#8221; \u2013 wie sich sp\u00e4ter herausstellen sollte, war das eine genauso wenig haltbare Aussage.) Im kommenden Oktober werde ich mich definitiv nicht mehr mit so einen Floskel abwimmeln lassen. Der &#8220;Verlust&#8221; des Rabenkalenders in diesem Jahr ist schon schmerzhaft. Mal schauen, ob ich doch noch einen auftreiben kann!<\/p>\n<p>Update 2013-01-07-14-30: Im Laden von Zweitausendeins im &#8220;Berliner Osten&#8221; (Friedrichstra\u00dfe 119) sind derzeit noch Exemplare (auch 3-er Pakete) vorr\u00e4tig.\t\t\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Raben-Kalender 2013 f\u00fcr 16.95 \u20ac Einige Tage vor Weihnachten rief ich noch im Landen in der Kantstra\u00dfe (Berlin-Charlottenburg) an mit den dringenden und konkreten Wunsch, mir ein 3-er Paket zur\u00fccklegen zu lassen. &#8220;Nein, nein, gar nicht n\u00f6tig, wir haben noch genug.&#8221; Und als ich dann kurz nach dem Jahreswechsel den Weg in den Laden fand, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_share_on_mastodon":"0"},"categories":[418],"tags":[],"class_list":["post-342","post","type-post","status-publish","format-standard","hentry","category-raben-kalender"],"share_on_mastodon":{"url":"","error":""},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paO0l8-5w","jetpack_likes_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/comments?post=342"}],"version-history":[{"count":0,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/342\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/media?parent=342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/categories?post=342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/tags?post=342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}