{"id":5177,"date":"2015-07-31T17:17:26","date_gmt":"2015-07-31T15:17:26","guid":{"rendered":"http:\/\/www.b.shuttle.de\/hayek\/hayek\/jochen\/wp\/blog-de\/?p=5177"},"modified":"2015-07-31T17:17:26","modified_gmt":"2015-07-31T15:17:26","slug":"demo-am-1-august-fur-grundrechte-und-pressefreiheit-gegen-die-einschuchterung-von-netzpolitik-org-und-seiner-quellen","status":"publish","type":"post","link":"https:\/\/wp.jochen.hayek.name\/blog-de\/2015\/07\/31\/demo-am-1-august-fur-grundrechte-und-pressefreiheit-gegen-die-einschuchterung-von-netzpolitik-org-und-seiner-quellen\/","title":{"rendered":"Demo am 1. August: f\u00fcr Grundrechte und Pressefreiheit \u2013 gegen die Einsch\u00fcchterung von netzpolitik.org und seiner Quellen"},"content":{"rendered":"<ul>\n<li><a href=\"https:\/\/netzpolitik.org\/2015\/demo-am-1-august-fuer-grundrechte-und-pressefreiheit-gegen-die-einschuechterung-von-netzpolitik-org-und-seiner-quellen\/\">https:\/\/netzpolitik.org\/2015\/demo-am-1-august-fuer-grundrechte-und-pressefreiheit-gegen-die-einschuechterung-von-netzpolitik-org-und-seiner-quellen\/<\/a><\/li>\n<\/ul>\n<p>Termin:\u00a0<span style=\"line-height: 1.6\">Samstag, 1. August 2015,\u00a0<\/span><span style=\"line-height: 1.6\">14 Uhr.<\/span><\/p>\n<p><span style=\"line-height: 1.6\">Die Route der Demo f\u00fchrt vom S-Bahnhof Friedrichstra\u00dfe, Dorothea-Schlegel-Platz, zum Justizministerium in der Mohrenstra\u00dfe.<\/span>\t\t\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/netzpolitik.org\/2015\/demo-am-1-august-fuer-grundrechte-und-pressefreiheit-gegen-die-einschuechterung-von-netzpolitik-org-und-seiner-quellen\/ Termin:\u00a0Samstag, 1. August 2015,\u00a014 Uhr. Die Route der Demo f\u00fchrt vom S-Bahnhof Friedrichstra\u00dfe, Dorothea-Schlegel-Platz, zum Justizministerium in der Mohrenstra\u00dfe.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_share_on_mastodon":"0"},"categories":[352],"tags":[],"class_list":["post-5177","post","type-post","status-publish","format-standard","hentry","category-nicht-zugeordnet"],"share_on_mastodon":{"url":"","error":""},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paO0l8-1lv","jetpack_likes_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/5177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/comments?post=5177"}],"version-history":[{"count":0,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/5177\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/media?parent=5177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/categories?post=5177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/tags?post=5177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}