{"id":5570,"date":"2016-01-16T14:51:23","date_gmt":"2016-01-16T13:51:23","guid":{"rendered":"http:\/\/www.b.shuttle.de\/hayek\/hayek\/jochen\/wp\/blog-de\/?p=5570"},"modified":"2016-01-16T14:51:23","modified_gmt":"2016-01-16T13:51:23","slug":"wochenend-beschaftigung-eines-wochenend-pendlers-wasche-waschen-und-so","status":"publish","type":"post","link":"https:\/\/wp.jochen.hayek.name\/blog-de\/2016\/01\/16\/wochenend-beschaftigung-eines-wochenend-pendlers-wasche-waschen-und-so\/","title":{"rendered":"Wochenend-Besch\u00e4ftigung eines Wochenend-Pendlers: W\u00e4sche-Waschen und so"},"content":{"rendered":"<p>\t\t\t\tIn der Waschmaschine steckt jetzt schon die 4. Ladung \u2013 aber sie wird sich erst in 8 Stunden starten \u2013 wenn sie fertig sein wird, soll ja auch schon wieder Platz auf den W\u00e4schest\u00e4ndern sein.<\/p>\n<p>Nein, W\u00e4sche-Waschen (etc.) ist keine schlimme Besch\u00e4ftigung \u2013 man muss sich einfach mental darauf einstellen, dass es gut und notwendig und ganz, ganz toll ist\u00a0 \ud83d\ude00\t\t\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In der Waschmaschine steckt jetzt schon die 4. Ladung \u2013 aber sie wird sich erst in 8 Stunden starten \u2013 wenn sie fertig sein wird, soll ja auch schon wieder Platz auf den W\u00e4schest\u00e4ndern sein. Nein, W\u00e4sche-Waschen (etc.) ist keine schlimme Besch\u00e4ftigung \u2013 man muss sich einfach mental darauf einstellen, dass es gut und notwendig [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_share_on_mastodon":"0"},"categories":[352],"tags":[],"class_list":["post-5570","post","type-post","status-publish","format-standard","hentry","category-nicht-zugeordnet"],"share_on_mastodon":{"url":"","error":""},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paO0l8-1rQ","jetpack_likes_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/5570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/comments?post=5570"}],"version-history":[{"count":0,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/5570\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/media?parent=5570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/categories?post=5570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/tags?post=5570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}