{"id":6054,"date":"2016-08-09T11:18:02","date_gmt":"2016-08-09T09:18:02","guid":{"rendered":"http:\/\/www.b.shuttle.de\/hayek\/hayek\/jochen\/wp\/blog-de\/?p=6054"},"modified":"2016-08-09T11:18:02","modified_gmt":"2016-08-09T09:18:02","slug":"neuer-job-neuer-firmenausweis-neues-bild","status":"publish","type":"post","link":"https:\/\/wp.jochen.hayek.name\/blog-de\/2016\/08\/09\/neuer-job-neuer-firmenausweis-neues-bild\/","title":{"rendered":"neuer Job \u2013 neuer Firmenausweis \u2013 neues Bild \u2013 kann ich das Bild als Datei bekommen? \u2013 \u2026 \u2013 N-E-I-N"},"content":{"rendered":"<ul>\n<li>neuer Job<\/li>\n<li>neuer Firmenausweis<\/li>\n<li>&#8220;geh zur Personalabteilung, ein neues Bild machen lassen!&#8221;<\/li>\n<li>Bild geschossen, beim 2. Versuch ganz ansehlich, n\u00e4mlich mit &#8220;Z\u00e4hne zeigen&#8221;, nicht gerade in die Kamera gucken, die Photographin kann man ja stattdessen auch angucken<\/li>\n<li>Kopf auf dem Bild-Ausschnitt nach meinen W\u00fcnschen positioniert (die Trennlinie zwischen dem mittleren und dem oberen Drittel geht sozusagen zentral durch meinen Kopf; auch nicht zu viel Drumherum \u00fcbrig lassen)<\/li>\n<li>Ausweis erstellt<\/li>\n<li>meine Frage: Kann ich das Bild als Datei bekommen?<\/li>\n<li>ihre Antwort: Wei\u00df nicht, wie das geht, ich geh mal fragen.<\/li>\n<li>sie geht fragen, sie kommt zur\u00fcck<\/li>\n<li>ihre Antwort: Wir wissen nicht, wo das abgelegt wird, geht nicht.<\/li>\n<li>meine Frage: &#8220;Alt+Print, Zwischenablage, mspaint, \u2026&#8221; \u2013 darf ich vielleicht selbst?<\/li>\n<li>ihre Antwort: N-E-I-N<\/li>\n<li>schade, das Bild ist eigentlich gut geworden<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>neuer Job neuer Firmenausweis &#8220;geh zur Personalabteilung, ein neues Bild machen lassen!&#8221; Bild geschossen, beim 2. Versuch ganz ansehlich, n\u00e4mlich mit &#8220;Z\u00e4hne zeigen&#8221;, nicht gerade in die Kamera gucken, die Photographin kann man ja stattdessen auch angucken Kopf auf dem Bild-Ausschnitt nach meinen W\u00fcnschen positioniert (die Trennlinie zwischen dem mittleren und dem oberen Drittel geht [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_share_on_mastodon":"0"},"categories":[352],"tags":[],"class_list":["post-6054","post","type-post","status-publish","format-standard","hentry","category-nicht-zugeordnet"],"share_on_mastodon":{"url":"","error":""},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paO0l8-1zE","jetpack_likes_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/6054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/comments?post=6054"}],"version-history":[{"count":0,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/6054\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/media?parent=6054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/categories?post=6054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/tags?post=6054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}