{"id":8885,"date":"2018-08-25T13:57:14","date_gmt":"2018-08-25T11:57:14","guid":{"rendered":"http:\/\/www.b.shuttle.de\/hayek\/hayek\/jochen\/wp\/blog-de\/?p=8885"},"modified":"2018-08-25T13:57:14","modified_gmt":"2018-08-25T11:57:14","slug":"schlafapnoe-syndrom","status":"publish","type":"post","link":"https:\/\/wp.jochen.hayek.name\/blog-de\/2018\/08\/25\/schlafapnoe-syndrom\/","title":{"rendered":"Schlafapnoe-Syndrom &#8211; periodische Atemstillst\u00e4nde w\u00e4hrend des Schlafs"},"content":{"rendered":"<ul>\n<li><a href=\"https:\/\/de.wikipedia.org\/wiki\/Schlafapnoe-Syndrom\">https:\/\/de.wikipedia.org\/wiki\/Schlafapnoe-Syndrom<\/a><\/li>\n<li><a href=\"https:\/\/en.wikipedia.org\/wiki\/Sleep_apnea\">https:\/\/en.wikipedia.org\/wiki\/Sleep_apnea<\/a><\/li>\n<li>ich?!?<\/li>\n<li>Formen und Ursachen; Symptome; Folgen; Diagnose; Behandlung<\/li>\n<li>O-M-G! so ein Mist!<\/li>\n<\/ul>\n<p>\u2026:<\/p>\n<ul>\n<li><a href=\"https:\/\/hno.charite.de\/leistungen\/schnarchen_und_schlaf_apnoe\/\">https:\/\/hno.charite.de\/leistungen\/schnarchen_und_schlaf_apnoe\/<\/a><\/li>\n<li><a href=\"https:\/\/schlafmedizin.charite.de\">https:\/\/schlafmedizin.charite.de<\/a>\u00a0\u2013 die HNO-Sprechstunde will bei Schlaf-Apnoe erst von dieser Stelle eine Analyse bekommen, bevor selbst auf den Patienten bzw. seinen Status eingegangen wird<\/li>\n<li><a href=\"https:\/\/hno.charite.de\/fuer_patienten\/sprechstunden\/\">https:\/\/hno.charite.de\/fuer_patienten\/sprechstunden\/<\/a> \u2013\u00a0privatversicherte Patienten werden zum\u00a0Campus Virchow-Klinikum (CVK), n\u00e4mlich zur\u00a0Privatsprechstunde von Frau Prof. Dr. Olze geleitet<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/de.wikipedia.org\/wiki\/Schlafapnoe-Syndrom https:\/\/en.wikipedia.org\/wiki\/Sleep_apnea ich?!? Formen und Ursachen; Symptome; Folgen; Diagnose; Behandlung O-M-G! so ein Mist! \u2026: https:\/\/hno.charite.de\/leistungen\/schnarchen_und_schlaf_apnoe\/ https:\/\/schlafmedizin.charite.de\u00a0\u2013 die HNO-Sprechstunde will bei Schlaf-Apnoe erst von dieser Stelle eine Analyse bekommen, bevor selbst auf den Patienten bzw. seinen Status eingegangen wird https:\/\/hno.charite.de\/fuer_patienten\/sprechstunden\/ \u2013\u00a0privatversicherte Patienten werden zum\u00a0Campus Virchow-Klinikum (CVK), n\u00e4mlich zur\u00a0Privatsprechstunde von Frau Prof. Dr. Olze geleitet<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"link","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_share_on_mastodon":"0"},"categories":[168],"tags":[1226,1227,1228],"class_list":["post-8885","post","type-post","status-publish","format-link","hentry","category-gesundheit","tag-schlaf","tag-schlaf-apnoe","tag-schlafapnoe","post_format-post-format-link"],"share_on_mastodon":{"url":"","error":""},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paO0l8-2jj","jetpack_likes_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/8885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/comments?post=8885"}],"version-history":[{"count":0,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/8885\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/media?parent=8885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/categories?post=8885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/tags?post=8885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}