{"id":9134,"date":"2018-11-06T16:44:19","date_gmt":"2018-11-06T15:44:19","guid":{"rendered":"http:\/\/www.b.shuttle.de\/hayek\/hayek\/jochen\/wp\/blog-de\/?p=9134"},"modified":"2021-04-06T19:47:36","modified_gmt":"2021-04-06T17:47:36","slug":"rossmann-ideenwelt-sandwichtoaster","status":"publish","type":"post","link":"https:\/\/wp.jochen.hayek.name\/blog-de\/2018\/11\/06\/rossmann-ideenwelt-sandwichtoaster\/","title":{"rendered":"Rossmann Ideenwelt Sandwichtoaster: Bedienungsanleitung"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/einkaufsportal.rossmann.de\/DesktopModules\/Webshop\/akte\/012547_G_1.pdf\">https:\/\/einkaufsportal.rossmann.de\/DesktopModules\/Webshop\/akte\/012547_G_1.pdf<\/a>&nbsp;\u2013 multi-lingual<\/li><li><a href=\"https:\/\/einkaufsportal.rossmann.de\/DesktopModules\/Webshop\/akte\/324298_G_1.pdf\">https:\/\/einkaufsportal.rossmann.de\/DesktopModules\/Webshop\/akte\/324298_G_1.pdf<\/a>&nbsp;\u2013 nur auf Deutsch<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn ich hier die Links festhalte, dann habe ich ein gutes Gef\u00fchl dabei, die Papierversion zu entsorgen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Update: Nach 2,5 Jahren im Einsatz zerbrach das gute Ding. Ich hatte das eigentlich schon viel fr\u00fcher erwartet. Beim regelm\u00e4\u00dfigen festen Dr\u00fccken, um es geschlossen zu bekommen, auch wenn es prall gef\u00fcllt war, sammelten sich mehr und mehr Risse. Das musste eines Tages zum &#8220;Bersten&#8221; f\u00fchren. Leider ist es zur Zeit nicht in meiner Filiale vorr\u00e4tig und nur bei einem Bestellwert ab \u20ac20 dorthin bestellbar. F\u00fcr knapp \u20ac5 Versandkosten h\u00e4tte ich es durchaus per DHL auch in eine Packstation liefern lassen k\u00f6nnen. Ich werde jetzt mal zur Konkurrenz im selben Hause (<a href=\"https:\/\/de.wikipedia.org\/wiki\/Europa-Center\">Europa-Center<\/a> in Berlin-Charlottenburg) wechseln \u2013 beim n\u00e4chsten Mal wird es dann vielleicht wieder dieses Produkt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/einkaufsportal.rossmann.de\/DesktopModules\/Webshop\/akte\/012547_G_1.pdf&nbsp;\u2013 multi-lingual https:\/\/einkaufsportal.rossmann.de\/DesktopModules\/Webshop\/akte\/324298_G_1.pdf&nbsp;\u2013 nur auf Deutsch Wenn ich hier die Links festhalte, dann habe ich ein gutes Gef\u00fchl dabei, die Papierversion zu entsorgen. Update: Nach 2,5 Jahren im Einsatz zerbrach das gute Ding. Ich hatte das eigentlich schon viel fr\u00fcher erwartet. Beim regelm\u00e4\u00dfigen festen Dr\u00fccken, um es geschlossen zu bekommen, auch wenn es prall gef\u00fcllt [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"link","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_share_on_mastodon":"0"},"categories":[195,272],"tags":[853],"class_list":["post-9134","post","type-post","status-publish","format-link","hentry","category-haushalt","category-kueche","tag-bedienungsanleitung","post_format-post-format-link"],"share_on_mastodon":{"url":"","error":""},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paO0l8-2nk","jetpack_likes_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/9134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/comments?post=9134"}],"version-history":[{"count":1,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/9134\/revisions"}],"predecessor-version":[{"id":11216,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/9134\/revisions\/11216"}],"wp:attachment":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/media?parent=9134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/categories?post=9134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/tags?post=9134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}