{"id":9703,"date":"2019-03-13T01:40:01","date_gmt":"2019-03-13T00:40:01","guid":{"rendered":"https:\/\/wp.jochen.hayek.eu\/blog-de\/?p=9703"},"modified":"2019-03-13T01:40:01","modified_gmt":"2019-03-13T00:40:01","slug":"raben-kalender-2019-02-26","status":"publish","type":"post","link":"https:\/\/wp.jochen.hayek.name\/blog-de\/2019\/03\/13\/raben-kalender-2019-02-26\/","title":{"rendered":"Kalender-Blatt vom 26. Februar 2019"},"content":{"rendered":"\n\t\t\t\t\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Nutze die gl\u00fccklichste Zeit deines Lebens, sie sind nur allzu kurz, jene gl\u00fccklichen Jahre unserer Lust! Sind wir gl\u00fccklich genug, sie genossen zu haben, tr\u00f6sten und erfreuen uns wonnevolle Erinnerungen noch im Alter. Haben wir sie vers\u00e4umt \u2026 bitteres Bedauern schreckliche Gewissensbisse zerrei\u00dfen uns dann, gesellen sich zu den Qualen des Alters und umgeben mit Tr\u00e4nen und Plagen das unheilvolle Nahen des Grabes \u2026 W\u00e4rest du so t\u00f6richt, an die Unsterblichkeit zu glauben?<\/p><cite>Marquis de Sade<\/cite><\/blockquote>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/de.wikipedia.org\/wiki\/Donatien_Alphonse_Fran\u00e7ois_de_Sade\">https:\/\/de.wikipedia.org\/wiki\/Donatien_Alphonse_Fran\u00e7ois_de_Sade<\/a><\/li><\/ul>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nutze die gl\u00fccklichste Zeit deines Lebens, sie sind nur allzu kurz, jene gl\u00fccklichen Jahre unserer Lust! Sind wir gl\u00fccklich genug, sie genossen zu haben, tr\u00f6sten und erfreuen uns wonnevolle Erinnerungen noch im Alter. Haben wir sie vers\u00e4umt \u2026 bitteres Bedauern schreckliche Gewissensbisse zerrei\u00dfen uns dann, gesellen sich zu den Qualen des Alters und umgeben mit [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"quote","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_share_on_mastodon":"0"},"categories":[418],"tags":[],"class_list":["post-9703","post","type-post","status-publish","format-quote","hentry","category-raben-kalender","post_format-post-format-quote"],"share_on_mastodon":{"url":"","error":""},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paO0l8-2wv","jetpack_likes_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/9703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/comments?post=9703"}],"version-history":[{"count":0,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/9703\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/media?parent=9703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/categories?post=9703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/tags?post=9703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}