{"id":9766,"date":"2019-03-14T14:25:13","date_gmt":"2019-03-14T13:25:13","guid":{"rendered":"https:\/\/wp.jochen.hayek.name\/blog-de\/?p=9766"},"modified":"2019-03-14T15:03:12","modified_gmt":"2019-03-14T14:03:12","slug":"meine-web-sachen-sind-erfolgreich-migriert","status":"publish","type":"post","link":"https:\/\/wp.jochen.hayek.name\/blog-de\/2019\/03\/14\/meine-web-sachen-sind-erfolgreich-migriert\/","title":{"rendered":"meine Web-Sachen sind erfolgreich migriert"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/wordpress.org\/download\/\">https:\/\/wordpress.org\/download\/<\/a><\/li><li><a href=\"https:\/\/www.mediawiki.org\/wiki\/Download\">https:\/\/www.mediawiki.org\/wiki\/Download<\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">So \u2026 \u2013 heute ist ein Grund zum Feiern \ud83e\udd42\ud83c\udf86 \u2013 ich habe meine Web-Sachen (WordPress, Mediawiki, normale Seiten) erfolgreich migriert. Auch das &#8220;Backupen&#8221; (und was alles dazu geh\u00f6rt) ist wieder am Laufen.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/wp.jochen.hayek.name\/blog-de\/\">https:\/\/wp.jochen.hayek.name\/blog-de\/<\/a><\/li><li><a href=\"https:\/\/wp.jochen.hayek.name\/blog-en\/\">https:\/\/wp.jochen.hayek.name\/blog-en\/<\/a><\/li><li><a href=\"https:\/\/wiki.jochen.hayek.name\/w\">https:\/\/wiki.jochen.hayek.name\/w<\/a><\/li><li><a href=\"https:\/\/hayek.name\">https:\/\/hayek.name<\/a><\/li><li><a href=\"https:\/\/jochen.hayek.name\">https:\/\/jochen.hayek.name<\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">In den n\u00e4chsten Tagen ist die E-Mail dran: alle Mail-Ordner von einem Server zum anderen \u00fcbertragen. eigentlich ein Klacks.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/de.wikipedia.org\/wiki\/Procmail\">https:\/\/de.wikipedia.org\/wiki\/Procmail<\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Die anstrengende Hauptarbeit habe ich bereits vor etlichen Tagen erledigt: meine Mail-Filter- und -Sortier-Regeln funktionieren ohne \u00c4nderung auf dem Zielsystem \ud83e\udd29 Das bedeutete aber durchaus eine Zeit m\u00fchseliger Experimente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abgesehen davon, dass ich migrieren musste, weil der alte Provider den Betrieb aufgibt, ist sogar beim neuen auch noch alles sch\u00f6ner. es hat nur eine Menge Zeit und Nerven gekostet \ud83d\ude30<br>aber wenn man&#8217;s dann mal hinter sich hat \u2026 \ud83d\ude01<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nun, ein paar TODOs wird&#8217;s schon noch geben:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Meine WordPress-Blogs verbreiten ihre (sic: <strong>meine<\/strong>) Posts noch nicht wieder automatisch nach Twitter, Facebook, \u2026<\/li><li>&#8220;Fr\u00fcher&#8221; war das bei meinen WordPress-Blogs mit den erlaubten Kommentatoren schon etwas sauberer und eingeschr\u00e4nkter.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Aspekt der Migration war auch, dass &#8220;hayek.name&#8221; (&#8220;DNS&#8221;) nicht einfach zu 100% in die neue Umgebung zu migrieren ist, da gibt es n\u00e4mlich z.B. etliche Subdomains, die von Google gemanaget werden \u2013 und weiterhin sollen.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>gapps.hayek.name \u2013 &#8220;Google Apps&#8221; \u2013 die Web-Seiten hat Google zwar abgestellt, aber die E-Mail, der Kalender, das Adressverzeichnis \u2026 funktionieren noch<\/li><li>meine alten Blogger.com-Blogs funktionieren anscheinend immer noch \u2013 und das sollen sie dann auch noch weiter<\/li><li>und eine Subdomain benutze ich DynDNS-m\u00e4\u00dfig, um mich mit einem h\u00fcbschen und einigerma\u00dfen kurzen Namen &#8220;zuhause&#8221; einloggen (etc.) zu k\u00f6nnen<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/wordpress.org\/download\/ https:\/\/www.mediawiki.org\/wiki\/Download So \u2026 \u2013 heute ist ein Grund zum Feiern \ud83e\udd42\ud83c\udf86 \u2013 ich habe meine Web-Sachen (WordPress, Mediawiki, normale Seiten) erfolgreich migriert. Auch das &#8220;Backupen&#8221; (und was alles dazu geh\u00f6rt) ist wieder am Laufen. https:\/\/wp.jochen.hayek.name\/blog-de\/ https:\/\/wp.jochen.hayek.name\/blog-en\/ https:\/\/wiki.jochen.hayek.name\/w https:\/\/hayek.name https:\/\/jochen.hayek.name In den n\u00e4chsten Tagen ist die E-Mail dran: alle Mail-Ordner von einem Server zum anderen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_share_on_mastodon":"0"},"categories":[1],"tags":[],"class_list":["post-9766","post","type-post","status-publish","format-standard","hentry","category-uncategorised"],"share_on_mastodon":{"url":"","error":""},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paO0l8-2xw","jetpack_likes_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/9766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/comments?post=9766"}],"version-history":[{"count":4,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/9766\/revisions"}],"predecessor-version":[{"id":9775,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/posts\/9766\/revisions\/9775"}],"wp:attachment":[{"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/media?parent=9766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/categories?post=9766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.jochen.hayek.name\/blog-de\/wp-json\/wp\/v2\/tags?post=9766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}